{"id":6932,"date":"2025-07-07T07:29:44","date_gmt":"2025-07-07T07:29:44","guid":{"rendered":"https:\/\/kpimining.com\/?p=6932"},"modified":"2025-07-08T05:27:03","modified_gmt":"2025-07-08T05:27:03","slug":"faits-saillants-de-la-journee-technique-cosmo-2025","status":"publish","type":"post","link":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/","title":{"rendered":"Faits saillants de la Journ\u00e9e technique COSMO 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6932\" class=\"elementor elementor-6932 elementor-6909\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b60e87 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6b60e87\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93e926c\" data-id=\"93e926c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebb191e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebb191e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e30b21e\" data-id=\"e30b21e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-047a54b elementor-widget elementor-widget-heading\" data-id=\"047a54b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faits saillants de la Journ\u00e9e technique COSMO 2025<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac62c0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac62c0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64decb6\" data-id=\"64decb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-265a473 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"265a473\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-13ed32d\" data-id=\"13ed32d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-490be8e elementor-widget elementor-widget-text-editor\" data-id=\"490be8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe 20 juin, notre \u00e9quipe a particip\u00e9 \u00e0 la Journ\u00e9e technique COSMO 2025 \u2014 un \u00e9v\u00e9nement qui a r\u00e9uni des chercheurs de premier plan et des leaders de l\u2019industrie qui repoussent les fronti\u00e8res de la planification mini\u00e8re stochastique, de la g\u00e9ostatistique et de l\u2019intelligence artificielle appliqu\u00e9e au secteur minier. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c229b4c elementor-widget elementor-widget-text-editor\" data-id=\"c229b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa journ\u00e9e a offert un m\u00e9lange riche de recherches de pointe et d\u2019applications concr\u00e8tes, mettant en lumi\u00e8re les derni\u00e8res avanc\u00e9es en planification mini\u00e8re stochastique, en techniques avanc\u00e9es de simulation g\u00e9ostatistique et en int\u00e9gration de l\u2019IA dans la planification mini\u00e8re. Elle a mis en \u00e9vidence l\u2019importance croissante de d\u00e9passer les hypoth\u00e8ses d\u00e9terministes et d\u2019adopter des m\u00e9thodes stochastiques pour quantifier et g\u00e9rer plus efficacement les incertitudes g\u00e9ologiques et op\u00e9rationnelles. L\u2019\u00e9v\u00e9nement a soulign\u00e9 \u00e0 la fois l\u2019impact concret de ces innovations sur les op\u00e9rations mini\u00e8res et les recherches de pointe men\u00e9es au laboratoire COSMO de l\u2019Universit\u00e9 McGill. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03722f1 elementor-widget elementor-widget-text-editor\" data-id=\"03722f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin: 0;\"><strong>Pr\u00e9sentations d\u2019applications industrielles<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dadaea2 elementor-widget elementor-widget-text-editor\" data-id=\"dadaea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCertaines \u00e9tudes de cas r\u00e9elles provenant d\u2019entreprises mini\u00e8res ont d\u00e9montr\u00e9 comment les m\u00e9thodes stochastiques et les simulations g\u00e9ostatistiques sont d\u00e9j\u00e0 utilis\u00e9es pour cr\u00e9er de la valeur, g\u00e9rer l\u2019incertitude et am\u00e9liorer la prise de d\u00e9cision : \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4804ae9 elementor-widget elementor-widget-text-editor\" data-id=\"4804ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin: 0;\"><strong>KPI Mining Solutions<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68dcd48 elementor-widget elementor-widget-text-editor\" data-id=\"68dcd48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Optimisation stochastique d\u2019un complexe minier de minerai de fer \u00e0 faible teneur<\/strong><\/div>\n\nUne \u00e9tude de cas men\u00e9e par l\u2019\u00e9quipe de KPI Mining s\u2019est concentr\u00e9e sur un gisement \u00e0 faible teneur, o\u00f9 le plan d\u00e9terministe conventionnel pr\u00e9sentait des risques importants, notamment en lien avec la contamination au soufre et la teneur pr\u00e9visionnelle en fer. De plus, des risques de dilution et de pertes de minerai ont \u00e9t\u00e9 identifi\u00e9s. Gr\u00e2ce \u00e0 l\u2019approche stochastique, l\u2019\u00e9quipe a \u00e9labor\u00e9 un plan minier plus robuste, \u00e0 partir duquel des phases op\u00e9rationnelles r\u00e9silientes au risque ont \u00e9t\u00e9 con\u00e7ues. Une r\u00e9optimisation par phase a ensuite \u00e9t\u00e9 effectu\u00e9e (toujours avec la m\u00e9thode stochastique) pour assurer une valeur maximale. Le plan final a d\u00e9montr\u00e9 une VAN 25 % plus \u00e9lev\u00e9e que le sc\u00e9nario de base conventionnel. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7974ed elementor-widget elementor-widget-image\" data-id=\"b7974ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"608\" src=\"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/CosmoDay-1.jpg\" class=\"attachment-full size-full wp-image-6916\" alt=\"\" srcset=\"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/CosmoDay-1.jpg 1600w, https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/CosmoDay-1-300x114.jpg 300w, https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/CosmoDay-1-1024x389.jpg 1024w, https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/CosmoDay-1-768x292.jpg 768w, https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/CosmoDay-1-1536x584.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6233ef elementor-widget elementor-widget-text-editor\" data-id=\"d6233ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin: 0;\"><strong>Vale Base Metals<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4201c9 elementor-widget elementor-widget-text-editor\" data-id=\"b4201c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Faire concorder les mod\u00e8les et les plans avec la r\u00e9alit\u00e9<\/strong><\/div>\nUne \u00e9tude de cas r\u00e9elle a permis de comparer les plans miniers stochastiques et d\u00e9terministes avec une zone d\u00e9j\u00e0 exploit\u00e9e, pour laquelle des donn\u00e9es de forage de production \u00e9taient disponibles (utilis\u00e9es comme meilleure approximation de la r\u00e9alit\u00e9). Les r\u00e9sultats ont montr\u00e9 une meilleure concordance des simulations g\u00e9ostatistiques avec la r\u00e9alit\u00e9, ainsi qu\u2019une pr\u00e9visibilit\u00e9 accrue des teneurs et tonnages gr\u00e2ce \u00e0 l\u2019optimisation stochastique.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d77921 elementor-widget elementor-widget-text-editor\" data-id=\"4d77921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Optimisation des forages de d\u00e9finition<\/strong><\/div>\nUne autre \u00e9tude de cas a mis en \u00e9vidence la puissance des approches stochastiques pour optimiser les forages de d\u00e9finition et les configurations de maillage.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8d46f7 elementor-widget elementor-widget-text-editor\" data-id=\"e8d46f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Risque sismique en milieu souterrain<\/strong><\/div>\nLes m\u00e9thodes stochastiques ont \u00e9galement \u00e9t\u00e9 utilis\u00e9es pour g\u00e9rer l\u2019incertitude li\u00e9e \u00e0 l\u2019activit\u00e9 sismique dans les mines souterraines profondes, permettant ainsi des plans de production plus fiables et moins sujets aux interruptions, avec une valeur accrue.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5321d68 elementor-widget elementor-widget-text-editor\" data-id=\"5321d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin: 0;\"><strong>Vale S.A.<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5475eb elementor-widget elementor-widget-text-editor\" data-id=\"e5475eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Gestion des \u00e9l\u00e9ments d\u00e9l\u00e9t\u00e8res \u00e0 l\u2019aide de m\u00e9thodes stochastiques<\/strong><\/div>\nUne \u00e9tude de cas portant sur un complexe minier de minerai de fer a r\u00e9v\u00e9l\u00e9, par analyse du plan d\u00e9terministe, une forte probabilit\u00e9 de sous-estimer les teneurs en contaminants. Pour att\u00e9nuer ces risques, des plans stochastiques ont \u00e9t\u00e9 \u00e9labor\u00e9s, am\u00e9liorant le contr\u00f4le des sp\u00e9cifications produit. Les r\u00e9sultats stochastiques ont \u00e9galement montr\u00e9 un potentiel accru de production de concentr\u00e9 de Fe, une VAN plus \u00e9lev\u00e9e et une dur\u00e9e de vie de mine prolong\u00e9e.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b31450b elementor-widget elementor-widget-text-editor\" data-id=\"b31450b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"margin: 0;\"><strong>Recherches en cours au laboratoire COSMO<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2f37f1 elementor-widget elementor-widget-text-editor\" data-id=\"d2f37f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Int\u00e9gration de la planification \u00e0 long et court terme sous incertitude<\/strong><\/div>\nUn projet remarquable portait sur l\u2019application des m\u00e9thodes stochastiques \u00e0 la planification int\u00e9gr\u00e9e \u00e0 long et court terme, tenant compte des incertitudes li\u00e9es \u00e0 la performance de l\u2019usine et \u00e0 la g\u00e9ologie, tout en int\u00e9grant les d\u00e9cisions d\u2019investissement (CAPEX). Ce mod\u00e8le assure que les op\u00e9rations atteignent leurs objectifs sur diff\u00e9rents horizons temporels.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c918ec7 elementor-widget elementor-widget-text-editor\" data-id=\"c918ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Int\u00e9gration de la restauration progressive et durabilit\u00e9<\/strong><\/div>\nL\u2019un des sujets les plus fascinants portait sur l\u2019int\u00e9gration de la restauration progressive directement dans la planification stochastique \u00e0 long terme. Un cadre a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour g\u00e9rer les mat\u00e9riaux potentiellement g\u00e9n\u00e9rateurs d\u2019acide, \u00e0 l\u2019aide d\u2019un encapsulage avec des mat\u00e9riaux non g\u00e9n\u00e9rateurs d\u2019acide. Dans une mine de cuivre, cela a permis de r\u00e9duire le co\u00fbt de transport par tonne extraite de 15 % et d\u2019augmenter la VAN de 4 %, d\u00e9montrant que la durabilit\u00e9 peut renforcer la rentabilit\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd08a9e elementor-widget elementor-widget-text-editor\" data-id=\"bd08a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Apprentissage de bout en bout pour l\u2019optimisation mini\u00e8re<\/strong><\/div>\nUne autre recherche ax\u00e9e sur l\u2019IA s\u2019est pench\u00e9e sur un cadre d\u2019apprentissage de bout en bout pour l\u2019optimisation mini\u00e8re, capable d\u2019\u00eatre entra\u00een\u00e9 sur des projets sp\u00e9cifiques afin de rendre les optimisations futures plus rapides et efficaces.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b965ef1 elementor-widget elementor-widget-text-editor\" data-id=\"b965ef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Planification \u00e0 court terme avec incertitude g\u00e9ologique<\/strong><\/div>\nUn autre projet innovant a permis d\u2019optimiser les syst\u00e8mes de gestion de flotte en tenant compte des incertitudes g\u00e9ologiques \u00e0 l\u2019\u00e9chelle de la planification \u00e0 court terme.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49d9dcd elementor-widget elementor-widget-text-editor\" data-id=\"49d9dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Flotte durable et optimisation \u00e0 court terme<\/strong><\/div>\nUn autre cadre d\u2019optimisation stochastique a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour optimiser conjointement la planification \u00e0 court terme et la gestion de la flotte, avec pour objectif de r\u00e9duire l\u2019empreinte carbone tout en maintenant la rentabilit\u00e9 \u2014 une d\u00e9monstration concr\u00e8te que l\u2019efficacit\u00e9 op\u00e9rationnelle et la durabilit\u00e9 peuvent aller de pair.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c705ffd elementor-widget elementor-widget-text-editor\" data-id=\"c705ffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Avanc\u00e9es dans les simulations g\u00e9ostatistiques<\/strong><\/div>\nLes recherches en cours ont aussi mis l\u2019accent sur l\u2019\u00e9volution des techniques de simulation g\u00e9ostatistique. Une \u00e9tude portait sur les m\u00e9thodes de simulation d\u2019ordre sup\u00e9rieur, capables de reproduire les statistiques d\u2019ordre sup\u00e9rieur des donn\u00e9es, sans faire appel aux hypoth\u00e8ses gaussiennes. Une autre s\u2019appuyait sur un mod\u00e8le g\u00e9n\u00e9ratif bas\u00e9 sur la reconnaissance de motifs, \u00e9liminant le besoin d\u2019une fonction de densit\u00e9 explicite.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4500098 elementor-widget elementor-widget-text-editor\" data-id=\"4500098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><strong>Optimisation mini\u00e8re souterraine<\/strong><\/div>\nL\u2019exploitation mini\u00e8re souterraine \u00e9tait \u00e9galement \u00e0 l\u2019honneur. Des m\u00e9thodes de r\u00e9solution avanc\u00e9es et efficaces sont en d\u00e9veloppement pour l\u2019optimisation stochastique conjointe de la conception et de la planification des chantiers souterrains, avec des r\u00e9sultats prometteurs \u00e0 la cl\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be89abc elementor-widget elementor-widget-text-editor\" data-id=\"be89abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChez KPI Mining, nous sommes ravis de voir l\u2019industrie progresser vers une planification mini\u00e8re plus robuste et consciente de l\u2019incertitude \u2014 une \u00e9volution en parfaite coh\u00e9rence avec notre mission. Nous sommes fiers d\u2019aider les entreprises mini\u00e8res \u00e0 \u00e9laborer des plans \u00e0 plus grande valeur, mieux r\u00e9silients face aux risques, en rendant accessibles des technologies avanc\u00e9es, appuy\u00e9es par la recherche, de mani\u00e8re concr\u00e8te et efficace. En transformant l\u2019innovation en solutions \u00e9prouv\u00e9es, nous permettons \u00e0 nos partenaires de g\u00e9n\u00e9rer de la valeur, de mieux g\u00e9rer les risques et de planifier avec plus de confiance. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le 20 juin, notre \u00e9quipe a particip\u00e9 \u00e0 la Journ\u00e9e technique COSMO 2025 \u2014 un \u00e9v\u00e9nement qui a r\u00e9uni des chercheurs de premier plan et des leaders de l\u2019industrie qui repoussent les fronti\u00e8res de la planification mini\u00e8re stochastique, de la g\u00e9ostatistique et de l\u2019intelligence artificielle appliqu\u00e9e au secteur minier.<\/p>\n","protected":false},"author":1,"featured_media":6965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[],"class_list":["post-6932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faits saillants de la Journ\u00e9e technique COSMO 2025 - KPI Mining Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faits saillants de la Journ\u00e9e technique COSMO 2025 - KPI Mining Solutions\" \/>\n<meta property=\"og:description\" content=\"Le 20 juin, notre \u00e9quipe a particip\u00e9 \u00e0 la Journ\u00e9e technique COSMO 2025 \u2014 un \u00e9v\u00e9nement qui a r\u00e9uni des chercheurs de premier plan et des leaders de l\u2019industrie qui repoussent les fronti\u00e8res de la planification mini\u00e8re stochastique, de la g\u00e9ostatistique et de l\u2019intelligence artificielle appliqu\u00e9e au secteur minier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"KPI Mining Solutions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KPIMining\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T07:29:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T05:27:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/COSMODay-2025-Thumbnail-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/#\\\/schema\\\/person\\\/97fe2efc4852e0ec0b4bef5ee973bb73\"},\"headline\":\"Faits saillants de la Journ\u00e9e technique COSMO 2025\",\"datePublished\":\"2025-07-07T07:29:44+00:00\",\"dateModified\":\"2025-07-08T05:27:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/\"},\"wordCount\":1222,\"publisher\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kpimining.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/COSMODay-2025-Thumbnail-1.jpg\",\"articleSection\":[\"\u00c9v\u00e9nements\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/\",\"url\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/\",\"name\":\"Faits saillants de la Journ\u00e9e technique COSMO 2025 - KPI Mining Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kpimining.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/COSMODay-2025-Thumbnail-1.jpg\",\"datePublished\":\"2025-07-07T07:29:44+00:00\",\"dateModified\":\"2025-07-08T05:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kpimining.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/COSMODay-2025-Thumbnail-1.jpg\",\"contentUrl\":\"https:\\\/\\\/kpimining.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/COSMODay-2025-Thumbnail-1.jpg\",\"width\":900,\"height\":456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/faits-saillants-de-la-journee-technique-cosmo-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kpimining.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faits saillants de la Journ\u00e9e technique COSMO 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/#website\",\"url\":\"https:\\\/\\\/kpimining.com\\\/\",\"name\":\"KPI Mining Solutions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kpimining.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/#organization\",\"name\":\"KPI Mining Solutions\",\"url\":\"https:\\\/\\\/kpimining.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kpimining.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/KPIMiningSolutions-Logo.png\",\"contentUrl\":\"https:\\\/\\\/kpimining.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/KPIMiningSolutions-Logo.png\",\"width\":500,\"height\":123,\"caption\":\"KPI Mining Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/kpimining.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KPIMining\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kpi-mining-solutions\",\"https:\\\/\\\/www.instagram.com\\\/kpiminingsolutions\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kpiminingsolutions4843\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kpimining.com\\\/#\\\/schema\\\/person\\\/97fe2efc4852e0ec0b4bef5ee973bb73\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c60456adc5c73de39aae9976efabf17714785c5621f99b9e627dd6bcab53f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c60456adc5c73de39aae9976efabf17714785c5621f99b9e627dd6bcab53f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c60456adc5c73de39aae9976efabf17714785c5621f99b9e627dd6bcab53f6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/kpimining.com\"],\"url\":\"https:\\\/\\\/kpimining.com\\\/fr\\\/author\\\/kpimining\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faits saillants de la Journ\u00e9e technique COSMO 2025 - KPI Mining Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Faits saillants de la Journ\u00e9e technique COSMO 2025 - KPI Mining Solutions","og_description":"Le 20 juin, notre \u00e9quipe a particip\u00e9 \u00e0 la Journ\u00e9e technique COSMO 2025 \u2014 un \u00e9v\u00e9nement qui a r\u00e9uni des chercheurs de premier plan et des leaders de l\u2019industrie qui repoussent les fronti\u00e8res de la planification mini\u00e8re stochastique, de la g\u00e9ostatistique et de l\u2019intelligence artificielle appliqu\u00e9e au secteur minier.","og_url":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/","og_site_name":"KPI Mining Solutions","article_publisher":"https:\/\/www.facebook.com\/KPIMining","article_published_time":"2025-07-07T07:29:44+00:00","article_modified_time":"2025-07-08T05:27:03+00:00","og_image":[{"width":900,"height":456,"url":"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/COSMODay-2025-Thumbnail-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#article","isPartOf":{"@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/"},"author":{"name":"admin","@id":"https:\/\/kpimining.com\/#\/schema\/person\/97fe2efc4852e0ec0b4bef5ee973bb73"},"headline":"Faits saillants de la Journ\u00e9e technique COSMO 2025","datePublished":"2025-07-07T07:29:44+00:00","dateModified":"2025-07-08T05:27:03+00:00","mainEntityOfPage":{"@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/"},"wordCount":1222,"publisher":{"@id":"https:\/\/kpimining.com\/#organization"},"image":{"@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/COSMODay-2025-Thumbnail-1.jpg","articleSection":["\u00c9v\u00e9nements"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/","url":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/","name":"Faits saillants de la Journ\u00e9e technique COSMO 2025 - KPI Mining Solutions","isPartOf":{"@id":"https:\/\/kpimining.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#primaryimage"},"image":{"@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/COSMODay-2025-Thumbnail-1.jpg","datePublished":"2025-07-07T07:29:44+00:00","dateModified":"2025-07-08T05:27:03+00:00","breadcrumb":{"@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#primaryimage","url":"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/COSMODay-2025-Thumbnail-1.jpg","contentUrl":"https:\/\/kpimining.com\/wp-content\/uploads\/2025\/07\/COSMODay-2025-Thumbnail-1.jpg","width":900,"height":456},{"@type":"BreadcrumbList","@id":"https:\/\/kpimining.com\/fr\/faits-saillants-de-la-journee-technique-cosmo-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kpimining.com\/"},{"@type":"ListItem","position":2,"name":"Faits saillants de la Journ\u00e9e technique COSMO 2025"}]},{"@type":"WebSite","@id":"https:\/\/kpimining.com\/#website","url":"https:\/\/kpimining.com\/","name":"KPI Mining Solutions","description":"","publisher":{"@id":"https:\/\/kpimining.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kpimining.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kpimining.com\/#organization","name":"KPI Mining Solutions","url":"https:\/\/kpimining.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kpimining.com\/#\/schema\/logo\/image\/","url":"https:\/\/kpimining.com\/wp-content\/uploads\/2023\/01\/KPIMiningSolutions-Logo.png","contentUrl":"https:\/\/kpimining.com\/wp-content\/uploads\/2023\/01\/KPIMiningSolutions-Logo.png","width":500,"height":123,"caption":"KPI Mining Solutions"},"image":{"@id":"https:\/\/kpimining.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KPIMining","https:\/\/www.linkedin.com\/company\/kpi-mining-solutions","https:\/\/www.instagram.com\/kpiminingsolutions\/","https:\/\/www.youtube.com\/@kpiminingsolutions4843"]},{"@type":"Person","@id":"https:\/\/kpimining.com\/#\/schema\/person\/97fe2efc4852e0ec0b4bef5ee973bb73","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f4c60456adc5c73de39aae9976efabf17714785c5621f99b9e627dd6bcab53f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4c60456adc5c73de39aae9976efabf17714785c5621f99b9e627dd6bcab53f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4c60456adc5c73de39aae9976efabf17714785c5621f99b9e627dd6bcab53f6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/kpimining.com"],"url":"https:\/\/kpimining.com\/fr\/author\/kpimining\/"}]}},"_links":{"self":[{"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/posts\/6932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/comments?post=6932"}],"version-history":[{"count":13,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/posts\/6932\/revisions"}],"predecessor-version":[{"id":6977,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/posts\/6932\/revisions\/6977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/media\/6965"}],"wp:attachment":[{"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/media?parent=6932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/categories?post=6932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kpimining.com\/fr\/wp-json\/wp\/v2\/tags?post=6932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}